{"id":7996,"date":"2022-05-25T00:00:00","date_gmt":"2022-05-24T22:00:00","guid":{"rendered":"https:\/\/guitrans.eus\/wp\/index.php\/2022\/05\/25\/acuerdo-provisional-sobre-un-entorno-de-ventanilla-unica-para-aduanas-de-la-ue\/"},"modified":"2022-05-25T00:00:00","modified_gmt":"2022-05-24T22:00:00","slug":"acuerdo-provisional-sobre-un-entorno-de-ventanilla-unica-para-aduanas-de-la-ue","status":"publish","type":"post","link":"https:\/\/www.guitrans.eus\/eu\/2022\/05\/25\/acuerdo-provisional-sobre-un-entorno-de-ventanilla-unica-para-aduanas-de-la-ue\/","title":{"rendered":"Acuerdo provisional sobre un Entorno de Ventanilla \u00danica para Aduanas de la UE"},"content":{"rendered":"<p>La Comisi\u00f3n Europea ha acogido el acuerdo pol\u00edtico provisional sobre la nueva iniciativa de ventanilla \u00fanica aduanera de la UE, que facilita a las diferentes autoridades implicadas en el despacho de mercanc\u00edas el intercambio de informaci\u00f3n electr\u00f3nica presentada por los comerciantes. Como siguiente paso, las empresas podr\u00e1n presentar la informaci\u00f3n reglamentaria y aduanera requerida para la importaci\u00f3n, el tr\u00e1nsito o la exportaci\u00f3n de mercanc\u00edas solo una vez a trav\u00e9s de un \u00fanico punto de entrada.<\/p>\n<p>El acuerdo al principio mejorar\u00e1 los intercambios entre gobiernos y permitir\u00e1 a las empresas y comerciantes recuperar documentos y autorizaciones aduaneras de los sistemas no aduaneros de la Uni\u00f3n, poni\u00e9ndolos a disposici\u00f3n de las aduanas nacionales de forma autom\u00e1tica y digital.  <\/p>\n<p>Una segunda fase pondr\u00e1 en marcha el esquema de empresa a gobierno que permite a los comerciantes proporcionar datos en un \u00fanico portal en un Estado miembro individual, evitando as\u00ed la necesidad de que utilicen sistemas no aduaneros y reduciendo la duplicaci\u00f3n, el tiempo y los costes. De esta forma, las aduanas y otras autoridades podr\u00e1n utilizar colectivamente estos datos, permitiendo un enfoque totalmente coordinado para el despacho de mercanc\u00edas y una visi\u00f3n m\u00e1s clara a nivel de la UE de las mercanc\u00edas que entran o salen de la UE.  <\/p>\n<p>Tras su adopci\u00f3n formal por el Parlamento Europeo y el Consejo, el componente intergubernamental de la ventanilla \u00fanica entrar\u00e1 en vigor en 2025, mientras que el r\u00e9gimen entre las empresas y las administraciones p\u00fablicas ser\u00e1 accesible en una fase posterior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una herramienta para racionalizar la cooperaci\u00f3n aduanera digital y facilitar el comercio. Actualmente, la importaci\u00f3n de bienes a la Uni\u00f3n involucra a muchas autoridades diferentes a cargo de diferentes \u00e1reas pol\u00edticas. Como resultado, las empresas tienen que enviar informaci\u00f3n, a menudo en papel, a varias autoridades diferentes, cada una con su propio portal y procedimientos.&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-7996","post","type-post","status-publish","format-standard","hentry","category-europa"],"_links":{"self":[{"href":"https:\/\/www.guitrans.eus\/eu\/wp-json\/wp\/v2\/posts\/7996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.guitrans.eus\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guitrans.eus\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guitrans.eus\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guitrans.eus\/eu\/wp-json\/wp\/v2\/comments?post=7996"}],"version-history":[{"count":0,"href":"https:\/\/www.guitrans.eus\/eu\/wp-json\/wp\/v2\/posts\/7996\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.guitrans.eus\/eu\/wp-json\/wp\/v2\/media?parent=7996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guitrans.eus\/eu\/wp-json\/wp\/v2\/categories?post=7996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guitrans.eus\/eu\/wp-json\/wp\/v2\/tags?post=7996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}